{"id":4290,"count":10,"description":"","link":"https:\/\/paule-vasseur.com\/en\/categorie-produit\/e-boutique\/jupes-et-pantalons\/","name":"Skirts and Trousers","slug":"jupes-et-pantalons","taxonomy":"product_cat","parent":4282,"meta":[],"menu_order":25,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jupes et Pantalons - PAULE VASSEUR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paule-vasseur.com\/en\/product-category\/online-shop\/jupes-et-pantalons\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jupes et Pantalons - PAULE VASSEUR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paule-vasseur.com\/en\/product-category\/online-shop\/jupes-et-pantalons\/\" \/>\n<meta property=\"og:site_name\" content=\"PAULE VASSEUR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/categorie-produit\\\/e-boutique\\\/jupes-et-pantalons\\\/\",\"url\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/categorie-produit\\\/e-boutique\\\/jupes-et-pantalons\\\/\",\"name\":\"Jupes et Pantalons - PAULE VASSEUR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/categorie-produit\\\/e-boutique\\\/jupes-et-pantalons\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/categorie-produit\\\/e-boutique\\\/jupes-et-pantalons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/paule-vasseur.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-Boutique Paule Vasseur\",\"item\":\"https:\\\/\\\/paule-vasseur.com\\\/categorie-produit\\\/e-boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jupes et Pantalons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/\",\"name\":\"RIDEAUX COUTURE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/#organization\",\"name\":\"RIDEAUX COUTURE\",\"url\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/paule-vasseur.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-cropped-logonew2018-2.webp\",\"contentUrl\":\"https:\\\/\\\/paule-vasseur.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-cropped-logonew2018-2.webp\",\"width\":166,\"height\":110,\"caption\":\"RIDEAUX COUTURE\"},\"image\":{\"@id\":\"https:\\\/\\\/paule-vasseur.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jupes et Pantalons - PAULE VASSEUR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paule-vasseur.com\/en\/product-category\/online-shop\/jupes-et-pantalons\/","og_locale":"en_GB","og_type":"article","og_title":"Jupes et Pantalons - PAULE VASSEUR","og_url":"https:\/\/paule-vasseur.com\/en\/product-category\/online-shop\/jupes-et-pantalons\/","og_site_name":"PAULE VASSEUR","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/paule-vasseur.com\/en\/categorie-produit\/e-boutique\/jupes-et-pantalons\/","url":"https:\/\/paule-vasseur.com\/en\/categorie-produit\/e-boutique\/jupes-et-pantalons\/","name":"Jupes et Pantalons - PAULE VASSEUR","isPartOf":{"@id":"https:\/\/paule-vasseur.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/paule-vasseur.com\/en\/categorie-produit\/e-boutique\/jupes-et-pantalons\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/paule-vasseur.com\/en\/categorie-produit\/e-boutique\/jupes-et-pantalons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/paule-vasseur.com\/"},{"@type":"ListItem","position":2,"name":"E-Boutique Paule Vasseur","item":"https:\/\/paule-vasseur.com\/categorie-produit\/e-boutique\/"},{"@type":"ListItem","position":3,"name":"Jupes et Pantalons"}]},{"@type":"WebSite","@id":"https:\/\/paule-vasseur.com\/en\/#website","url":"https:\/\/paule-vasseur.com\/en\/","name":"SEWN CURTAINS","description":"","publisher":{"@id":"https:\/\/paule-vasseur.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paule-vasseur.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/paule-vasseur.com\/en\/#organization","name":"SEWN CURTAINS","url":"https:\/\/paule-vasseur.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/paule-vasseur.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/paule-vasseur.com\/wp-content\/uploads\/2025\/09\/cropped-cropped-logonew2018-2.webp","contentUrl":"https:\/\/paule-vasseur.com\/wp-content\/uploads\/2025\/09\/cropped-cropped-logonew2018-2.webp","width":166,"height":110,"caption":"RIDEAUX COUTURE"},"image":{"@id":"https:\/\/paule-vasseur.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/paule-vasseur.com\/en\/wp-json\/wp\/v2\/product_cat\/4290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paule-vasseur.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/paule-vasseur.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/paule-vasseur.com\/en\/wp-json\/wp\/v2\/product_cat\/4282"}],"wp:post_type":[{"href":"https:\/\/paule-vasseur.com\/en\/wp-json\/wp\/v2\/product?product_cat=4290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}